{"id":2209,"date":"2024-07-22T15:29:30","date_gmt":"2024-07-22T13:29:30","guid":{"rendered":"https:\/\/even-tech.fr\/?p=2209"},"modified":"2024-07-22T16:09:00","modified_gmt":"2024-07-22T14:09:00","slug":"gala-danse-carignan-de-bordeaux-eventech","status":"publish","type":"post","link":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/","title":{"rendered":"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2209\" class=\"elementor elementor-2209\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-95d3d51 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no\" data-id=\"95d3d51\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3c53e3f\" data-id=\"3c53e3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4142eb elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f4142eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1d14a59 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no\" data-id=\"1d14a59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5725e17\" data-id=\"5725e17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0815ca8 elementor-invisible elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"0815ca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-206bfef elementor-invisible elementor-widget elementor-widget-post-info\" data-id=\"206bfef\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-495ecd7 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-calendar-alt\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M148 288h-40c-6.6 0-12-5.4-12-12v-40c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v40c0 6.6-5.4 12-12 12zm108-12v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 96v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm-96 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm192 0v-40c0-6.6-5.4-12-12-12h-40c-6.6 0-12 5.4-12 12v40c0 6.6 5.4 12 12 12h40c6.6 0 12-5.4 12-12zm96-260v352c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h48V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h128V12c0-6.6 5.4-12 12-12h40c6.6 0 12 5.4 12 12v52h48c26.5 0 48 21.5 48 48zm-48 346V160H48v298c0 3.3 2.7 6 6 6h340c3.3 0 6-2.7 6-6z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>07\/22\/2024<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a0929d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no\" data-id=\"a0929d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1661592\" data-id=\"1661592\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76d3a38 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"76d3a38\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"451\" src=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448741931_973847224750626_5348952764110586655_n-1024x577.jpg\" class=\"attachment-large size-large wp-image-2218\" alt=\"Gala Carignan de Bordeaux - eventech - sonorisation - mise en lumi\u00e8re - vid\u00e9o\" srcset=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448741931_973847224750626_5348952764110586655_n-1024x577.jpg 1024w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448741931_973847224750626_5348952764110586655_n-300x169.jpg 300w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448741931_973847224750626_5348952764110586655_n-768x432.jpg 768w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448741931_973847224750626_5348952764110586655_n-1536x865.jpg 1536w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448741931_973847224750626_5348952764110586655_n.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-334ec2a\" data-id=\"334ec2a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6311164 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6311164\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"451\" src=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448742687_973847241417291_352129881369573550_n-1024x577.jpg\" class=\"attachment-large size-large wp-image-2219\" alt=\"Gala Carignan de Bordeaux - eventech - sonorisation - mise en lumi\u00e8re - vid\u00e9o\" srcset=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448742687_973847241417291_352129881369573550_n-1024x577.jpg 1024w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448742687_973847241417291_352129881369573550_n-300x169.jpg 300w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448742687_973847241417291_352129881369573550_n-768x432.jpg 768w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448742687_973847241417291_352129881369573550_n-1536x865.jpg 1536w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448742687_973847241417291_352129881369573550_n.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1274f48 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1274f48\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sonorisation et mise en lumi\u00e8re pour Eventech ! <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19c7c6d elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"19c7c6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Au mois de Juin, la soci\u00e9t\u00e9 Eventech a eu l&#8217;honneur de prendre en charge la r\u00e9gie technique d&#8217;un gala de danse et de com\u00e9die \u00e0 Carignan de Bordeaux.<\/p><p>Cet \u00e9v\u00e9nement a rassembl\u00e9 des artistes et des spectateurs passionn\u00e9s. Dans cet article, nous vous d\u00e9voilons les coulisses de cette prestation technique, en vous expliquant les d\u00e9fis et les solutions mises en place pour assurer une sonorisation et un \u00e9clairage impeccables.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9cb109e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9cb109e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Sonorisation : L'Art de la Clart\u00e9 Sonore<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-788222c elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"788222c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour un gala de danse et de com\u00e9die, la qualit\u00e9 sonore est primordiale. Elle permet aux spectateurs de profiter pleinement des performances artistiques, que ce soit pour la musique, les dialogues ou les effets sonores.<\/p><ul><li><p><strong>Installation du Mat\u00e9riel : <\/strong><\/p><\/li><\/ul><p><strong>Haut-parleurs :<\/strong> Des enceintes de haute qualit\u00e9 ont \u00e9t\u00e9 install\u00e9es \u00e0 des points strat\u00e9giques de la salle pour assurer une diffusion sonore homog\u00e8ne.<\/p><p><strong>Microphones :<\/strong> Des microphones sans fil et filaires ont \u00e9t\u00e9 dispos\u00e9s pour capter les voix des artistes et les sons d&#8217;ambiance. Les micros-cravates ont \u00e9t\u00e9 utilis\u00e9s pour les com\u00e9diens afin de garantir une libert\u00e9 de mouvement.<\/p><p><strong>Table de Mixage :<\/strong> Une console de mixage num\u00e9rique a \u00e9t\u00e9 utilis\u00e9e pour contr\u00f4ler le volume, les effets et l&#8217;\u00e9quilibre des diff\u00e9rentes sources sonores.<\/p><ul><li><p><strong>Gestion en Direct :<\/strong><\/p><\/li><\/ul><p><strong>Ing\u00e9nieur du Son :<\/strong> Un ing\u00e9nieur du son a supervis\u00e9 le mixage en direct, ajustant les niveaux sonores en temps r\u00e9el pour s&#8217;adapter aux diff\u00e9rentes performances et assurer une qualit\u00e9 optimale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c96a382 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"c96a382\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448740602_973847151417300_4422884060355527571_n-1024x577.jpg\" alt=\"Gala Carignan de Bordeaux\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448741931_973847224750626_5348952764110586655_n-1024x577.jpg\" alt=\"Gala Carignan de Bordeaux - eventech - sonorisation - mise en lumi\u00e8re - vid\u00e9o\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448742687_973847241417291_352129881369573550_n-1024x577.jpg\" alt=\"Gala Carignan de Bordeaux - eventech - sonorisation - mise en lumi\u00e8re - vid\u00e9o\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/449117663_973847108083971_8514403103302711247_n-1024x460.jpg\" alt=\"Gala Carignan de Bordeaux - eventech - sonorisation - mise en lumi\u00e8re - vid\u00e9o\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-155d05e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"155d05e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'\u00c9clairage : Mettre en Lumi\u00e8re les \u00c9motions<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-467101f elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"467101f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;\u00e9clairage joue un r\u00f4le essentiel dans la cr\u00e9ation de l&#8217;atmosph\u00e8re et l&#8217;accentuation des moments cl\u00e9s d&#8217;un spectacle de danse et de com\u00e9die.<\/p><ul><li><p><strong>Conception Lumineuse :<\/strong><\/p><\/li><\/ul><p><strong>Projecteurs :<\/strong> Des projecteurs LED et des lyres motoris\u00e9es ont \u00e9t\u00e9 dispos\u00e9s pour offrir une flexibilit\u00e9 maximale dans les effets lumineux. Les projecteurs ont \u00e9t\u00e9 programm\u00e9s pour suivre les mouvements des danseurs et les entr\u00e9es\/sorties des com\u00e9diens.<\/p><p><strong>\u00c9clairages d&#8217;Ambiance :<\/strong> Des lumi\u00e8res d&#8217;ambiance ont \u00e9t\u00e9 utilis\u00e9es pour cr\u00e9er des atmosph\u00e8res vari\u00e9es, allant des sc\u00e8nes intimistes aux tableaux dynamiques et color\u00e9s.<\/p><ul><li><strong>Contr\u00f4le et Programmation :<\/strong><\/li><\/ul><p>\u00a0<\/p><p><strong>Console d&#8217;\u00c9clairage :<\/strong> Une console d&#8217;\u00e9clairage DMX a permis de programmer des s\u00e9quences lumineuses complexes et de les d\u00e9clencher en synchronisation avec la musique et les actions sur sc\u00e8ne.<\/p><p><strong>Techniciens Lumi\u00e8re :<\/strong> Une \u00e9quipe de techniciens a supervis\u00e9 l&#8217;\u00e9clairage en direct, ajustant les intensit\u00e9s et les couleurs en fonction des besoins de chaque sc\u00e8ne pour renforcer l&#8217;impact visuel.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8723f91\" data-id=\"8723f91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2ecfbb6 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no elementor-invisible\" data-id=\"2ecfbb6\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-705745b\" data-id=\"705745b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9b8c12 elementor-search-form--skin-classic elementor-search-form--button-type-icon elementor-search-form--icon-search elementor-widget elementor-widget-search-form\" data-id=\"c9b8c12\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;classic&quot;}\" data-widget_type=\"search-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<search role=\"search\">\n\t\t\t<form class=\"elementor-search-form\" action=\"https:\/\/even-tech.fr\" method=\"get\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-search-form__container\">\n\t\t\t\t\t<label class=\"elementor-screen-only\" for=\"elementor-search-form-c9b8c12\">Search<\/label>\n\n\t\t\t\t\t\n\t\t\t\t\t<input id=\"elementor-search-form-c9b8c12\" placeholder=\"Recherche...\" class=\"elementor-search-form__input\" type=\"search\" name=\"s\" value=\"\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<button class=\"elementor-search-form__submit\" type=\"submit\" aria-label=\"Search\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"e-font-icon-svg-container\"><svg class=\"fa fa-search e-font-icon-svg e-fas-search\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M505 442.7L405.3 343c-4.5-4.5-10.6-7-17-7H372c27.6-35.3 44-79.7 44-128C416 93.1 322.9 0 208 0S0 93.1 0 208s93.1 208 208 208c48.3 0 92.7-16.4 128-44v16.3c0 6.4 2.5 12.5 7 17l99.7 99.7c9.4 9.4 24.6 9.4 33.9 0l28.3-28.3c9.4-9.4 9.4-24.6.1-34zM208 336c-70.7 0-128-57.2-128-128 0-70.7 57.2-128 128-128 70.7 0 128 57.2 128 128 0 70.7-57.2 128-128 128z\"><\/path><\/svg><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/form>\n\t\t<\/search>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5c90d5c elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no elementor-invisible\" data-id=\"5c90d5c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9351c00\" data-id=\"9351c00\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7eb2d96 elementor-widget elementor-widget-heading\" data-id=\"7eb2d96\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos derniers articles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fc9a1a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3fc9a1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5eb5943 elementor-grid-1 elementor-posts--thumbnail-left elementor-grid-tablet-1 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"5eb5943\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;20&quot;,&quot;sizes&quot;:[]},&quot;classic_columns_tablet&quot;:&quot;1&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-1982 post type-post status-publish format-standard has-post-thumbnail hentry category-actus category-nos-clients\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/even-tech.fr\/index.php\/2024\/05\/21\/eventech-a-la-foire-de-la-saint-fort\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405485-300x200.jpg\" class=\"attachment-medium size-medium wp-image-1983\" alt=\"Eventech - Sonorisation de la foire de la st fort - Saint denis de Pile\" srcset=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405485-300x200.jpg 300w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405485-1024x683.jpg 1024w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405485-768x512.jpg 768w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405485-1536x1024.jpg 1536w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405485-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/even-tech.fr\/index.php\/2024\/05\/21\/eventech-a-la-foire-de-la-saint-fort\/\" >\n\t\t\t\t\u00c9ventech \u00e0 la foire de la Saint Fort !\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 May 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2025 post type-post status-publish format-standard has-post-thumbnail hentry category-nos-clients\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/even-tech.fr\/index.php\/2024\/05\/21\/jubile-de-christophe-gameiro\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405463-300x200.jpg\" class=\"attachment-medium size-medium wp-image-2027\" alt=\"Sonorisation du Jubil\u00e9 de Christophe Gameiro au lyc\u00e9e montagne - Eventech\" srcset=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405463-300x200.jpg 300w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405463-1024x683.jpg 1024w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405463-768x512.jpg 768w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405463-1536x1024.jpg 1536w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/A7405463-2048x1365.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/even-tech.fr\/index.php\/2024\/05\/21\/jubile-de-christophe-gameiro\/\" >\n\t\t\t\tJubil\u00e9 de Christophe Gameiro\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t21 May 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-2078 post type-post status-publish format-standard has-post-thumbnail hentry category-nos-clients\" role=\"listitem\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/even-tech.fr\/index.php\/2024\/05\/30\/concert-symphonique-eventech\/\" tabindex=\"-1\" >\n\t\t\t<div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/B7E00008-AB36-481D-BEE9-6AF70A6AC0AC-300x169.jpeg\" class=\"attachment-medium size-medium wp-image-2080\" alt=\"Sonorisation Orchestre Symphonique Saint Germain du Puch - eventech Bordeaux\" srcset=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/B7E00008-AB36-481D-BEE9-6AF70A6AC0AC-300x169.jpeg 300w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/B7E00008-AB36-481D-BEE9-6AF70A6AC0AC-1024x577.jpeg 1024w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/B7E00008-AB36-481D-BEE9-6AF70A6AC0AC-768x432.jpeg 768w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/B7E00008-AB36-481D-BEE9-6AF70A6AC0AC-1536x865.jpeg 1536w, https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/05\/B7E00008-AB36-481D-BEE9-6AF70A6AC0AC.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div>\n\t\t<\/a>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/even-tech.fr\/index.php\/2024\/05\/30\/concert-symphonique-eventech\/\" >\n\t\t\t\tConcert symphonique &#8211; Eventech\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__meta-data\">\n\t\t\t\t\t<span class=\"elementor-post-date\">\n\t\t\t30 May 2024\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c0dcf94 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no wpr-equal-height-no elementor-invisible\" data-id=\"c0dcf94\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2407d37\" data-id=\"2407d37\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22f67b8 elementor-widget elementor-widget-heading\" data-id=\"22f67b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9seaux sociaux<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e5a141 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"0e5a141\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be68152 e-grid-align-left elementor-shape-rounded elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"be68152\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-8f9485a\" href=\"https:\/\/www.facebook.com\/profile.php?id=61558870601855\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-4f68f17\" href=\"https:\/\/www.instagram.com\/eventech_bdx\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-e204e71\" href=\"https:\/\/www.linkedin.com\/company\/%C3%A9ventech\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech Sonorisation et mise en lumi\u00e8re pour Eventech ! Au mois de Juin, la soci\u00e9t\u00e9 Eventech a eu l&#8217;honneur de prendre en charge la r\u00e9gie technique d&#8217;un gala de danse et de com\u00e9die \u00e0 Carignan de Bordeaux. Cet \u00e9v\u00e9nement a rassembl\u00e9 des artistes et des spectateurs passionn\u00e9s. Dans cet article, nous vous d\u00e9voilons les coulisses de cette prestation technique, en vous expliquant les d\u00e9fis et les solutions mises en place pour assurer une sonorisation et un \u00e9clairage impeccables. La Sonorisation : L&#8217;Art de la Clart\u00e9 Sonore Pour un gala de danse et de com\u00e9die, la qualit\u00e9 sonore est primordiale. Elle permet aux spectateurs de profiter pleinement des performances artistiques, que ce soit pour la musique, les dialogues ou les effets sonores. Installation du Mat\u00e9riel : Haut-parleurs : Des enceintes de haute qualit\u00e9 ont \u00e9t\u00e9 install\u00e9es \u00e0 des points strat\u00e9giques de la salle pour assurer une diffusion sonore homog\u00e8ne. Microphones : Des microphones sans fil et filaires ont \u00e9t\u00e9 dispos\u00e9s pour capter les voix des artistes et les sons d&#8217;ambiance. Les micros-cravates ont \u00e9t\u00e9 utilis\u00e9s pour les com\u00e9diens afin de garantir une libert\u00e9 de mouvement. Table de Mixage : Une console de mixage num\u00e9rique a \u00e9t\u00e9 utilis\u00e9e pour contr\u00f4ler le volume, les effets et l&#8217;\u00e9quilibre des diff\u00e9rentes sources sonores. Gestion en Direct : Ing\u00e9nieur du Son : Un ing\u00e9nieur du son a supervis\u00e9 le mixage en direct, ajustant les niveaux sonores en temps r\u00e9el pour s&#8217;adapter aux diff\u00e9rentes performances et assurer une qualit\u00e9 optimale. L&#8217;\u00c9clairage : Mettre en Lumi\u00e8re les \u00c9motions L&#8217;\u00e9clairage joue un r\u00f4le essentiel dans la cr\u00e9ation de l&#8217;atmosph\u00e8re et l&#8217;accentuation des moments cl\u00e9s d&#8217;un spectacle de danse et de com\u00e9die. Conception Lumineuse : Projecteurs : Des projecteurs LED et des lyres motoris\u00e9es ont \u00e9t\u00e9 dispos\u00e9s pour offrir une flexibilit\u00e9 maximale dans les effets lumineux. Les projecteurs ont \u00e9t\u00e9 programm\u00e9s pour suivre les mouvements des danseurs et les entr\u00e9es\/sorties des com\u00e9diens. \u00c9clairages d&#8217;Ambiance : Des lumi\u00e8res d&#8217;ambiance ont \u00e9t\u00e9 utilis\u00e9es pour cr\u00e9er des atmosph\u00e8res vari\u00e9es, allant des sc\u00e8nes intimistes aux tableaux dynamiques et color\u00e9s. Contr\u00f4le et Programmation : \u00a0 Console d&#8217;\u00c9clairage : Une console d&#8217;\u00e9clairage DMX a permis de programmer des s\u00e9quences lumineuses complexes et de les d\u00e9clencher en synchronisation avec la musique et les actions sur sc\u00e8ne. Techniciens Lumi\u00e8re : Une \u00e9quipe de techniciens a supervis\u00e9 l&#8217;\u00e9clairage en direct, ajustant les intensit\u00e9s et les couleurs en fonction des besoins de chaque sc\u00e8ne pour renforcer l&#8217;impact visuel. Nos derniers articles R\u00e9seaux sociaux Facebook Instagram Linkedin<\/p>\n","protected":false},"author":1,"featured_media":2180,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[8,7],"tags":[],"class_list":["post-2209","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actus","category-nos-clients"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech<\/title>\n<meta name=\"description\" content=\"Au mois de Juin, la soci\u00e9t\u00e9 Eventech a eu l\u2019honneur de prendre en charge la r\u00e9gie technique d\u2019un gala de danse et de com\u00e9die \u00e0 Carignan de Bordeaux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech\" \/>\n<meta property=\"og:description\" content=\"Au mois de Juin, la soci\u00e9t\u00e9 Eventech a eu l\u2019honneur de prendre en charge la r\u00e9gie technique d\u2019un gala de danse et de com\u00e9die \u00e0 Carignan de Bordeaux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/\" \/>\n<meta property=\"og:site_name\" content=\"even-tech.fr\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-22T13:29:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-22T14:09:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448740602_973847151417300_4422884060355527571_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1153\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"even-tech.fr\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"even-tech.fr\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/\"},\"author\":{\"name\":\"even-tech.fr\",\"@id\":\"https:\\\/\\\/even-tech.fr\\\/#\\\/schema\\\/person\\\/bc2da0a259dc56b180a39acc1482338e\"},\"headline\":\"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech\",\"datePublished\":\"2024-07-22T13:29:30+00:00\",\"dateModified\":\"2024-07-22T14:09:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/\"},\"wordCount\":469,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/even-tech.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/448740602_973847151417300_4422884060355527571_n.jpg\",\"articleSection\":[\"ACTUS\",\"NOS CLIENTS\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/\",\"url\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/\",\"name\":\"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/even-tech.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/448740602_973847151417300_4422884060355527571_n.jpg\",\"datePublished\":\"2024-07-22T13:29:30+00:00\",\"dateModified\":\"2024-07-22T14:09:00+00:00\",\"description\":\"Au mois de Juin, la soci\u00e9t\u00e9 Eventech a eu l\u2019honneur de prendre en charge la r\u00e9gie technique d\u2019un gala de danse et de com\u00e9die \u00e0 Carignan de Bordeaux.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/#primaryimage\",\"url\":\"https:\\\/\\\/even-tech.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/448740602_973847151417300_4422884060355527571_n.jpg\",\"contentUrl\":\"https:\\\/\\\/even-tech.fr\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/448740602_973847151417300_4422884060355527571_n.jpg\",\"width\":2048,\"height\":1153,\"caption\":\"Gala Carignan de Bordeaux\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/2024\\\/07\\\/22\\\/gala-danse-carignan-de-bordeaux-eventech\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/even-tech.fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/even-tech.fr\\\/#website\",\"url\":\"https:\\\/\\\/even-tech.fr\\\/\",\"name\":\"even-tech.fr\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/even-tech.fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/even-tech.fr\\\/#organization\",\"name\":\"even-tech.fr\",\"url\":\"https:\\\/\\\/even-tech.fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/even-tech.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/even-tech.fr\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Fichier-11.png\",\"contentUrl\":\"https:\\\/\\\/even-tech.fr\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Fichier-11.png\",\"width\":1159,\"height\":557,\"caption\":\"even-tech.fr\"},\"image\":{\"@id\":\"https:\\\/\\\/even-tech.fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/even-tech.fr\\\/#\\\/schema\\\/person\\\/bc2da0a259dc56b180a39acc1482338e\",\"name\":\"even-tech.fr\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8472ae85ec9323583d07b58d52fa5b8d5dbdb1a0093b937d5f437d7e039d3ecb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8472ae85ec9323583d07b58d52fa5b8d5dbdb1a0093b937d5f437d7e039d3ecb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8472ae85ec9323583d07b58d52fa5b8d5dbdb1a0093b937d5f437d7e039d3ecb?s=96&d=mm&r=g\",\"caption\":\"even-tech.fr\"},\"sameAs\":[\"http:\\\/\\\/even-tech.fr\"],\"url\":\"https:\\\/\\\/even-tech.fr\\\/index.php\\\/author\\\/even-tech-fr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech","description":"Au mois de Juin, la soci\u00e9t\u00e9 Eventech a eu l\u2019honneur de prendre en charge la r\u00e9gie technique d\u2019un gala de danse et de com\u00e9die \u00e0 Carignan de Bordeaux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/","og_locale":"en_US","og_type":"article","og_title":"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech","og_description":"Au mois de Juin, la soci\u00e9t\u00e9 Eventech a eu l\u2019honneur de prendre en charge la r\u00e9gie technique d\u2019un gala de danse et de com\u00e9die \u00e0 Carignan de Bordeaux.","og_url":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/","og_site_name":"even-tech.fr","article_published_time":"2024-07-22T13:29:30+00:00","article_modified_time":"2024-07-22T14:09:00+00:00","og_image":[{"width":2048,"height":1153,"url":"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448740602_973847151417300_4422884060355527571_n.jpg","type":"image\/jpeg"}],"author":"even-tech.fr","twitter_card":"summary_large_image","twitter_misc":{"Written by":"even-tech.fr","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/#article","isPartOf":{"@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/"},"author":{"name":"even-tech.fr","@id":"https:\/\/even-tech.fr\/#\/schema\/person\/bc2da0a259dc56b180a39acc1482338e"},"headline":"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech","datePublished":"2024-07-22T13:29:30+00:00","dateModified":"2024-07-22T14:09:00+00:00","mainEntityOfPage":{"@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/"},"wordCount":469,"commentCount":0,"publisher":{"@id":"https:\/\/even-tech.fr\/#organization"},"image":{"@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/#primaryimage"},"thumbnailUrl":"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448740602_973847151417300_4422884060355527571_n.jpg","articleSection":["ACTUS","NOS CLIENTS"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/","url":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/","name":"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech","isPartOf":{"@id":"https:\/\/even-tech.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/#primaryimage"},"image":{"@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/#primaryimage"},"thumbnailUrl":"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448740602_973847151417300_4422884060355527571_n.jpg","datePublished":"2024-07-22T13:29:30+00:00","dateModified":"2024-07-22T14:09:00+00:00","description":"Au mois de Juin, la soci\u00e9t\u00e9 Eventech a eu l\u2019honneur de prendre en charge la r\u00e9gie technique d\u2019un gala de danse et de com\u00e9die \u00e0 Carignan de Bordeaux.","breadcrumb":{"@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/#primaryimage","url":"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448740602_973847151417300_4422884060355527571_n.jpg","contentUrl":"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/07\/448740602_973847151417300_4422884060355527571_n.jpg","width":2048,"height":1153,"caption":"Gala Carignan de Bordeaux"},{"@type":"BreadcrumbList","@id":"https:\/\/even-tech.fr\/index.php\/2024\/07\/22\/gala-danse-carignan-de-bordeaux-eventech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/even-tech.fr\/"},{"@type":"ListItem","position":2,"name":"Un gala de danse \u00e0 Carignan-de-Bordeaux avec \u00c9ventech"}]},{"@type":"WebSite","@id":"https:\/\/even-tech.fr\/#website","url":"https:\/\/even-tech.fr\/","name":"even-tech.fr","description":"","publisher":{"@id":"https:\/\/even-tech.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/even-tech.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/even-tech.fr\/#organization","name":"even-tech.fr","url":"https:\/\/even-tech.fr\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/even-tech.fr\/#\/schema\/logo\/image\/","url":"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/04\/Fichier-11.png","contentUrl":"https:\/\/even-tech.fr\/wp-content\/uploads\/2024\/04\/Fichier-11.png","width":1159,"height":557,"caption":"even-tech.fr"},"image":{"@id":"https:\/\/even-tech.fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/even-tech.fr\/#\/schema\/person\/bc2da0a259dc56b180a39acc1482338e","name":"even-tech.fr","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8472ae85ec9323583d07b58d52fa5b8d5dbdb1a0093b937d5f437d7e039d3ecb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8472ae85ec9323583d07b58d52fa5b8d5dbdb1a0093b937d5f437d7e039d3ecb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8472ae85ec9323583d07b58d52fa5b8d5dbdb1a0093b937d5f437d7e039d3ecb?s=96&d=mm&r=g","caption":"even-tech.fr"},"sameAs":["http:\/\/even-tech.fr"],"url":"https:\/\/even-tech.fr\/index.php\/author\/even-tech-fr\/"}]}},"_links":{"self":[{"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/posts\/2209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/comments?post=2209"}],"version-history":[{"count":25,"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/posts\/2209\/revisions"}],"predecessor-version":[{"id":2238,"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/posts\/2209\/revisions\/2238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/media\/2180"}],"wp:attachment":[{"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/media?parent=2209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/categories?post=2209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/even-tech.fr\/index.php\/wp-json\/wp\/v2\/tags?post=2209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}